{"id":6185,"date":"2018-06-06T20:13:50","date_gmt":"2018-06-07T01:13:50","guid":{"rendered":"https:\/\/www.arquidiocesismty.org\/arquimty\/?p=6185"},"modified":"2018-06-06T20:13:50","modified_gmt":"2018-06-07T01:13:50","slug":"185-aniversario-de-la-catedral-de-monterrey","status":"publish","type":"post","link":"https:\/\/www.arquidiocesismty.org\/arquimty\/185-aniversario-de-la-catedral-de-monterrey\/","title":{"rendered":"185 aniversario de la Catedral de Monterrey"},"content":{"rendered":"<div id=\"js_7qx\" class=\"_5pbx userContent _3576\" data-ft=\"{&quot;tn&quot;:&quot;K&quot;}\">\n<div id=\"id_5b1815f391ecf3560084015\" class=\"text_exposed_root text_exposed\">\n<p><strong>Por Juan Pablo V\u00e1zquez Rodr\u00edguez<\/strong><\/p>\n<p><strong>Monterrey, N.L. (<a href=\"http:\/\/www.arquidiocesismty.org\/\" target=\"_blank\" rel=\"noopener nofollow\" data-ft=\"{&quot;tn&quot;:&quot;-U&quot;}\" data-lynx-mode=\"async\" data-lynx-uri=\"https:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Fwww.arquidiocesismty.org%2F&amp;h=ATNtoFM_JxLInc44elMqgxXsio-uwwcoOSNSXZtZrLL47ya-a_FBHjT-byDyXOq1GbDfQkp2q_BDxvVCjDNZ4NWcepWuUNlZXf8XSOlbk5vOR_gx8zJwt6UVbUld_PRuQUdY0UkWn_hrdV5r6UWs1Pn6\">www.arquidiocesismty.org<\/a>).- 3 de junio 2018.<\/strong> Este domingo, la comunidad cat\u00f3lica, celebr\u00f3 el 185 aniversario de la consagraci\u00f3n de la Catedral Metropolitana de Monterrey, con la celebraci\u00f3n de la Santa Misa, presidida por el Arzobispo de Monterrey.<\/p>\n<div class=\"text_exposed_show\">\n<p>\u201cAgradezcamos a Dios estos 185 a\u00f1os de nuestra Iglesia Catedral, imag\u00ednense cuantos a\u00f1os, cuantos fieles, cuantas Eucarist\u00edas se han celebrado en este lugar, cuanta alabanza para Dios, cuanta santidad\u201d.<\/p>\n<p>Al referirse a la Palbra de Dios se\u00f1al\u00f3 que, \u201cquien esta con Cristo puede ser feliz\u201d.<\/p>\n<p>\u201cDios nos ha querido cuidar, poner en el centro de la creaci\u00f3n, porque nos ama y porque gozamos su vida\u201d.<\/p>\n<p>\u201cEl dijo, el s\u00e1bado se hizo para el hombre, no el hombre para el s\u00e1bado\u201d.<\/p>\n<p>\u201cAprovechemos el descanso para amar y convivir con nuestra familia, que amar no se convierta en esclavitud, que no te estreses demasiado, que recuperes las fuerzas f\u00edsicas para amar y servir a tu familia, y desde luego servir a Cristo\u201d.<br \/>\n<a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/iglesiademonterrey?source=feed_text\" data-ft=\"{&quot;tn&quot;:&quot;*N&quot;,&quot;type&quot;:104}\"><span class=\"_5afx\"><span class=\"_58cl _5afz\" aria-label=\"numeral\">#<\/span><span class=\"_58cm\">IglesiaDeMonterrey<\/span><\/span><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"_3x-2\" data-ft=\"{&quot;tn&quot;:&quot;H&quot;}\">\n<div data-ft=\"{&quot;tn&quot;:&quot;H&quot;}\">\n<div class=\"mtm\">\n<div class=\"_2a2q _65sr\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Juan Pablo V\u00e1zquez Rodr\u00edguez Monterrey, N.L. (www.arquidiocesismty.org).- 3 de junio 2018. Este domingo, la comunidad cat\u00f3lica, celebr\u00f3 el 185 aniversario de la consagraci\u00f3n de la<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":6186,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/6185"}],"collection":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/comments?post=6185"}],"version-history":[{"count":1,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/6185\/revisions"}],"predecessor-version":[{"id":6187,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/6185\/revisions\/6187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media\/6186"}],"wp:attachment":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media?parent=6185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/categories?post=6185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/tags?post=6185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}