{"id":5603,"date":"2018-04-30T22:35:16","date_gmt":"2018-05-01T03:35:16","guid":{"rendered":"https:\/\/www.arquidiocesismty.org\/arquimty\/?p=5603"},"modified":"2018-05-04T12:26:26","modified_gmt":"2018-05-04T17:26:26","slug":"vivan-su-infancia-con-mucha-alegria-arzobispo-de-monterrey","status":"publish","type":"post","link":"https:\/\/www.arquidiocesismty.org\/arquimty\/vivan-su-infancia-con-mucha-alegria-arzobispo-de-monterrey\/","title":{"rendered":"\u201cVivan su infancia con mucha alegr\u00eda\u201d, Arzobispo de Monterrey"},"content":{"rendered":"<p><strong>Monterrey, N.L. <\/strong><\/p>\n<p>(<a href=\"http:\/\/www.pastoralsiglo21.org\/\">www.pastoralsiglo21.org<\/a>)\u00a0<strong>30 de abril del 2018.-<\/strong> Con motivo de la celebraci\u00f3n del D\u00eda del Ni\u00f1o, Mons. Rogelio felicit\u00f3 a todos los ni\u00f1os y los invit\u00f3 a vivir plenamente esta etapa.<\/p>\n<p>\u201cDeseo enviar un mensaje no solo de felicitaci\u00f3n por su d\u00eda, sino de petici\u00f3n para que sigan viviendo su infancia con mucha alegr\u00eda, con ilusi\u00f3n, siempre tomados de la mano de sus pap\u00e1s, confiando en ellos, platic\u00e1ndoles todo\u00a0<span class=\"textexposedshow\">lo que les pasa\u201d.<\/span><\/p>\n<p>\u201cLes invit\u00f3 a que nunca dejen de decirle a sus pap\u00e1s lo que tienen en su coraz\u00f3n, las cosas que viven, sean buenas o sean malas, ya que es muy importante que vean a sus pap\u00e1s como los mejores amigos, los que nunca les abandonar\u00e1n y siempre les ayudar\u00e1n a ser mejores personas\u201d.<\/p>\n<p>Asimismo, el Arzobispo aconsej\u00f3 a los padres de familia para que dediquen todo el tiempo que sea necesario a sus hijos.<\/p>\n<p>\u201cSomos conscientes de los grandes peligros a los que est\u00e1 expuesta la infancia en nuestro tiempo, por lo que se hace m\u00e1s urgente el poner atenci\u00f3n a los m\u00e1s peque\u00f1os\u201d.<\/p>\n<p>Finalmente, el Arzobispo invit\u00f3 a todos a no olvidar a los ni\u00f1os que viven en situaciones vulnerables, que son abandonados y que necesitan el apoyo de la sociedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey, N.L. (www.pastoralsiglo21.org)\u00a030 de abril del 2018.- Con motivo de la celebraci\u00f3n del D\u00eda del Ni\u00f1o, Mons. Rogelio felicit\u00f3 a todos los ni\u00f1os y los invit\u00f3<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":5605,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,16,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/5603"}],"collection":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/comments?post=5603"}],"version-history":[{"count":2,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/5603\/revisions"}],"predecessor-version":[{"id":5651,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/5603\/revisions\/5651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media\/5605"}],"wp:attachment":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media?parent=5603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/categories?post=5603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/tags?post=5603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}