{"id":5592,"date":"2018-04-30T22:19:03","date_gmt":"2018-05-01T03:19:03","guid":{"rendered":"https:\/\/www.arquidiocesismty.org\/arquimty\/?p=5592"},"modified":"2018-04-30T22:19:25","modified_gmt":"2018-05-01T03:19:25","slug":"donde-no-hay-esperanza-donde-no-hay-fe-en-dios-es-muy-dificil-ser-feliz","status":"publish","type":"post","link":"https:\/\/www.arquidiocesismty.org\/arquimty\/donde-no-hay-esperanza-donde-no-hay-fe-en-dios-es-muy-dificil-ser-feliz\/","title":{"rendered":"\u201cDonde no hay esperanza, donde no hay fe en dios, es muy dif\u00edcil ser feliz\u201d"},"content":{"rendered":"<p>Monterrey, N.L.\u00a030 de abril 2018. El pasado domingo se llev\u00f3 a cabo el Encuentro Juvenil de la Zona Pastoral XII, con Mons. Rogelio Cabrera L\u00f3pez Arzobispo de Monterrey.<\/p>\n<p>El Encuentro tuvo lugar en en el Centro Cat\u00f3lico de Reconciliaci\u00f3n, Camino a Zir\u00e1ndaro en Benito Ju\u00e1rez, N.L., donde los j\u00f3venes tuvieron la oportunidad de orar, compartir y celebrar<span class=\"text_exposed_show\">\u00a0la santa Misa.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>Mons. Rogelio dialog\u00f3 con los j\u00f3venes, respondi\u00f3 algunas preguntas y les animo a seguir en el camino de la fe.<\/p>\n<p>\u201cDonde no hay esperanza, donde no hay fe en Dios, es muy dif\u00edcil ser feliz\u201d, se\u00f1al\u00f3<\/p>\n<p>\u201cLa fe hay que pedirla, esa no la conquistamos nosotros, es un regalo de Dios y hay que pedirle siempre al Se\u00f1or, que crea, que crea en ti, es lo primero que hay que hacer, pedir la fe\u201d, porque en cada persona aunque se vivan circustancias parecidas, reacciona de manera distinta ante la vida\u201d<\/p>\n<p>\u201cSegundo, hay que preparar el terreno para recibirla, con la Palabra de Dios, escucharla, dice San Pablo que la fe viene de o\u00edr la predicaci\u00f3n y esta consiste en hablar de Cristo, solo les pido estas dos cosas\u201d.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey, N.L.\u00a030 de abril 2018. El pasado domingo se llev\u00f3 a cabo el Encuentro Juvenil de la Zona Pastoral XII, con Mons. Rogelio Cabrera L\u00f3pez Arzobispo<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":5590,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,16,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/5592"}],"collection":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/comments?post=5592"}],"version-history":[{"count":1,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/5592\/revisions"}],"predecessor-version":[{"id":5593,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/5592\/revisions\/5593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media\/5590"}],"wp:attachment":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media?parent=5592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/categories?post=5592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/tags?post=5592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}