{"id":15070,"date":"2021-12-05T18:00:49","date_gmt":"2021-12-05T18:00:49","guid":{"rendered":"https:\/\/www.arquidiocesismty.org\/arquimty\/?p=15070"},"modified":"2021-12-06T13:12:02","modified_gmt":"2021-12-06T19:12:02","slug":"felicita-arzobispo-a-voluntarios-en-su-dia","status":"publish","type":"post","link":"https:\/\/www.arquidiocesismty.org\/arquimty\/felicita-arzobispo-a-voluntarios-en-su-dia\/","title":{"rendered":"FELICITA ARZOBISPO A VOLUNTARIOS EN SU D\u00cdA"},"content":{"rendered":"<p><em>Por: Juan Pablo V\u00e1zquez Rodr\u00edguez<\/em><br \/>\n<em>Monterrey, N.L. (www.pastoralsiglo21.org).- 06 de diciembre del 2021<\/em><\/p>\n<p><strong>Al celebrarse este domingo el D\u00eda del Voluntario, el Arzobispo de Monterrey, envi\u00f3 una felicitaci\u00f3n y agradecimiento a todos los que realizan alguna actividad de apoyo social.<\/strong><\/p>\n<p>\u201cEl d\u00eda de hoy se celebra internacionalmente el D\u00eda del Voluntario, es mi deber agradecer a tantos hombres y tantas mujeres que en todo el mundo, en M\u00e9xico y que de modo especial en Nuevo Le\u00f3n se distinguen por su capacidad altruista llena de caridad.<\/p>\n<p>\u201cGracias a los voluntarios se atienden a los migrantes, a los ni\u00f1os y ni\u00f1as m\u00e1s necesitados y a todas las personas que por alguna raz\u00f3n no pueden resolver sus propios problemas\u201d.<\/p>\n<p>\u201cEsta metr\u00f3poli, son ciudades que tienen muy dentro del coraz\u00f3n la capacidad para ser voluntarios\u201d, a\u00f1adi\u00f3 Don Rogelio.<\/p>\n<p><strong>\u201cEl voluntariado que brota de un amor sincero, pero que tambi\u00e9n brota desde la caridad del Evangelio es muy provechoso para la sociedad\u201d.<\/strong><\/p>\n<p>El Arzobispo, pidi\u00f3 a los gobernantes ser facilitadores del trabajo de voluntariado ciudadano.<\/p>\n<p>\u201cPido a los gobernantes, en todos sus niveles, que apoyen a los voluntarios, M\u00e9xico necesita de los ciudadanos, necesita de la actividad altruista de todos y para ello a la autoridad le toca facilitar y no estorbar\u201d.<\/p>\n<p>Finalmente, a\u00f1adi\u00f3: \u201cQue Dios bendiga a todos y gracias a ustedes hombres y mujeres por ayudar\u201d.<\/p>\n<p>#IglesiaDeMonterrey<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Juan Pablo V\u00e1zquez Rodr\u00edguez Monterrey, N.L. (www.pastoralsiglo21.org).- 06 de diciembre del 2021 Al celebrarse este domingo el D\u00eda del Voluntario, el Arzobispo de Monterrey, envi\u00f3<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":15072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15070"}],"collection":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/comments?post=15070"}],"version-history":[{"count":1,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15070\/revisions"}],"predecessor-version":[{"id":15071,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15070\/revisions\/15071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media\/15072"}],"wp:attachment":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media?parent=15070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/categories?post=15070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/tags?post=15070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}