{"id":15055,"date":"2021-11-30T17:00:57","date_gmt":"2021-11-30T17:00:57","guid":{"rendered":"https:\/\/www.arquidiocesismty.org\/arquimty\/?p=15055"},"modified":"2021-12-01T01:37:53","modified_gmt":"2021-12-01T07:37:53","slug":"nueva-zona-y-nuevo-decanato-pastoral-en-la-arquidiocesis-de-monterrey","status":"publish","type":"post","link":"https:\/\/www.arquidiocesismty.org\/arquimty\/nueva-zona-y-nuevo-decanato-pastoral-en-la-arquidiocesis-de-monterrey\/","title":{"rendered":"NUEVA ZONA Y NUEVO DECANATO PASTORAL EN LA ARQUIDI\u00d3CESIS DE MONTERREY"},"content":{"rendered":"<p><em>Por: Juan Pablo V\u00e1zquez Rodr\u00edguez <\/em><br \/>\n<em>Monterrey, N.L. (www.pastoralsiglo21.org).- 30 de noviembre del 2021<\/em><\/p>\n<p><strong>El Arzobispo de Monterrey, Mons. Rogelio Cabrera L\u00f3pez, dio a conocer mediante un decreto que, debido al aumento considerable de la poblaci\u00f3n de nuestra Arquidi\u00f3cesis se ha visto la necesidad de erigir nuevas parroquias y misiones parroquiales para atender mejor a los fieles y reestructurar nuevas zonas pastorales.<\/strong><\/p>\n<p>Por tal motivo, nuestro pastor, despu\u00e9s de haber escuchado el parecer del Consejo Presbiteral y haber consultado al consejo episcopal, ha visto conveniente crear una zona pastoral nueva y hacer una modificaci\u00f3n en el Decanato de Garc\u00eda y en el Decanato de San Jos\u00e9.<\/p>\n<p>Esta nueva zona se desprende casi en su totalidad de la Zona Pastoral XIII y una parroquia de la Zona Pastoral X.<\/p>\n<p>La Zona Pastoral XIII se llamar\u00e1 a partir de que entre en vigor el decreto Zona Pastoral XIII (Valle de las Salinas) y la nueva Zona se llamar\u00e1: Zona Pastoral XIV (Nororiente del Estado).<\/p>\n<p>As\u00ed mismo, Mons. Cabrera ha decidido crear un decanato nuevo llamado Decanato de Loreto que quedar\u00e1 en la Zona Pastoral XIV (Nororiente del Estado).<\/p>\n<p>???? ???????? ???? (Valle de las Salinas)<\/p>\n<p>???????? ?? ???????<\/p>\n<p>Misio\u0301n parroquial San Jose\u0301 Sa\u0301nchez del Ri\u0301o (El Carmen)<\/p>\n<p>Parroquia Nuestra Sen\u0303ora del Pueblito (Hidalgo)<\/p>\n<p>Parroquia Nuestra Sen\u0303ora de Guadalupe (El Carmen)<\/p>\n<p>Parroquia Nuestra Sen\u0303ora de Guadalupe (Mina)<\/p>\n<p>???????? ??????? ????????<\/p>\n<p>Parroquia San Jose\u0301 Nuestro Padre y Sen\u0303or (Cie\u0301nega de Flores)<\/p>\n<p>Parroquia Sagrado Corazo\u0301n de Jesu\u0301s (Salinas Victoria)<\/p>\n<p>Parroquia San Eloy (Cie\u0301nega de Flores)<\/p>\n<p>Parroquia Nuestra Sen\u0303ora de Guadalupe (Salinas Victoria)<\/p>\n<p>???? ???????? ??? (Norponiente del Estado)<\/p>\n<p>???????? ?? ??????<\/p>\n<p>Parroquia Nuestra Sen\u0303ora del Roble (Pesqueri\u0301a)<\/p>\n<p>Parroquia El Sen\u0303or de la Misericordia (Pesqueri\u0301a)<\/p>\n<p>Misio\u0301n parroquial San Marti\u0301n Caballero (Pesqueri\u0301a)<\/p>\n<p>Parroquia Nuestra Sen\u0303ora de Loreto (Pesqueri\u0301a)<\/p>\n<p>???????? ?? ???\u00ed?<\/p>\n<p>Parroquia San Judas Tadeo y San Simo\u0301n, Apo\u0301stoles (Cie\u0301nega de Flores)<\/p>\n<p>Parroquia Jesu\u0301s Misericordioso (Gral. Zuazua)<\/p>\n<p>Parroquia Santa Elena de la Cruz (Gral. Zuazua)<\/p>\n<p>Parroquia Nuestra Sen\u0303ora de la Asuncio\u0301n (Mari\u0301n)<\/p>\n<p>Misio\u0301n parroquial Todos los Santos (Gral. Zuazua)<\/p>\n<p>Con este decreto Mons. Rogelio, busca impulsar la acci\u00f3n pastoral en nuestra Arquidi\u00f3cesis y atender mejor a todos los fieles que conforman la Arquidi\u00f3cesis de Monterrey.<\/p>\n<p>#IglesiaDeMonterrey<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Juan Pablo V\u00e1zquez Rodr\u00edguez Monterrey, N.L. (www.pastoralsiglo21.org).- 30 de noviembre del 2021 El Arzobispo de Monterrey, Mons. Rogelio Cabrera L\u00f3pez, dio a conocer mediante un<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":15057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15055"}],"collection":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/comments?post=15055"}],"version-history":[{"count":1,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15055\/revisions"}],"predecessor-version":[{"id":15056,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15055\/revisions\/15056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media\/15057"}],"wp:attachment":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media?parent=15055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/categories?post=15055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/tags?post=15055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}