{"id":15046,"date":"2021-11-25T15:20:41","date_gmt":"2021-11-25T15:20:41","guid":{"rendered":"https:\/\/www.arquidiocesismty.org\/arquimty\/?p=15046"},"modified":"2021-11-25T15:32:15","modified_gmt":"2021-11-25T21:32:15","slug":"grupos-religiosos-se-manifiestan-en-contra-de-la-reforma-al-articulo-6o-constitucional-el-cual-pone-en-riesgo-la-libertad-religiosa","status":"publish","type":"post","link":"https:\/\/www.arquidiocesismty.org\/arquimty\/grupos-religiosos-se-manifiestan-en-contra-de-la-reforma-al-articulo-6o-constitucional-el-cual-pone-en-riesgo-la-libertad-religiosa\/","title":{"rendered":"GRUPOS RELIGIOSOS SE MANIFIESTAN EN CONTRA DE LA REFORMA AL ART\u00cdCULO 6\u00ba CONSTITUCIONAL EL CUAL PONE EN RIESGO LA LIBERTAD RELIGIOSA"},"content":{"rendered":"<p><em>Por: Juan Pablo V\u00e1zquez Rodr\u00edguez <\/em><br \/>\n<em>Monterrey, N.L. (www.pastoralsiglo21.org).- 25 de noviembre del 2021<\/em><\/p>\n<p><strong>Hace una semana se dio a conocer la sanci\u00f3n a 3 Obispos de parte del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n, por exhortar a los fieles a no votar por promotores del aborto. Y en torno al 5\u00ba Congreso Nacional sobre Libertad Religiosa, Mons. Pedro Pablo Elizondo declar\u00f3 que seg\u00fan el \u00faltimo censo de poblaci\u00f3n y vivienda el 93 % de la poblaci\u00f3n profesa alguna religi\u00f3n.<\/strong><\/p>\n<p>\u201cManifestamos que el sector religioso en nuestro pa\u00eds es preponderante en las diferentes esferas de la actividad humana. De igual forma este sector es tambi\u00e9n un capital social, cultural y de diversidad&#8221;.<\/p>\n<p>Los Consejos Interreligiosos, participantes del Congreso son grupos integrados por las diversas Agrupaciones y Asociaciones religiosas de las religiones preponderantes que existen en M\u00e9xico donde participan hombres y mujeres, cuyo objetivo es promover y defender la libertad religiosa, la tolerancia y la colaboraci\u00f3n religiosa.<\/p>\n<p>En torno al 5\u00ba Congreso Nacional sobre Libertad Religiosa, los representantes de los diversos grupos manifestaron ante los medios de comunicaci\u00f3n presentes, su preocupaci\u00f3n ante las diversas iniciativas legislativas que se encuentran en discusi\u00f3n en las c\u00e1maras federales y locales, ya que se pretende despenalizar el aborto y restringir la libertad de expresi\u00f3n, lo que puede vulnerar y amenazar los derechos y libertades del sector religioso y sus comunidades. Adem\u00e1s de que en M\u00e9xico, la segunda causa de discriminaci\u00f3n es por motivos religiosos. Siendo tambi\u00e9n, posible que a partir de estas restricciones al sector religioso, estas se extiendan a la ciudadan\u00eda en general e incluso a los medios de comunicaci\u00f3n.<\/p>\n<p>Ante todo esto, los diversos Consejos Interreligiosos alrededor del pa\u00eds, trabajan en conjunto y en armon\u00eda, preparando agendas y planes de acci\u00f3n sobre estos temas, en las que se incluyen di\u00e1logos con funcionarios p\u00fablicos, foros y seminarios a lo largo y ancho de la Rep\u00fablica, ruedas de prensa y desplegados de prensa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Juan Pablo V\u00e1zquez Rodr\u00edguez Monterrey, N.L. (www.pastoralsiglo21.org).- 25 de noviembre del 2021 Hace una semana se dio a conocer la sanci\u00f3n a 3 Obispos de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":15048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[110,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15046"}],"collection":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/comments?post=15046"}],"version-history":[{"count":1,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15046\/revisions"}],"predecessor-version":[{"id":15047,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/15046\/revisions\/15047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media\/15048"}],"wp:attachment":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media?parent=15046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/categories?post=15046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/tags?post=15046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}