{"id":14049,"date":"2021-03-13T09:49:33","date_gmt":"2021-03-13T15:49:33","guid":{"rendered":"https:\/\/www.arquidiocesismty.org\/arquimty\/?p=14049"},"modified":"2021-03-13T09:49:33","modified_gmt":"2021-03-13T15:49:33","slug":"octavo-aniversario-del-pontificado-del-papa-francisco","status":"publish","type":"post","link":"https:\/\/www.arquidiocesismty.org\/arquimty\/octavo-aniversario-del-pontificado-del-papa-francisco\/","title":{"rendered":"OCTAVO ANIVERSARIO DEL PONTIFICADO DEL PAPA FRANCISCO"},"content":{"rendered":"<p><strong>Por Juan Pablo V\u00e1zquez Rodr\u00edguez<\/strong><br \/>\n<strong>Monterrey, N.L. (www.pastoralsiglo21.org).- 13 de marzo del 2021<\/strong><\/p>\n<p>El 13 de marzo de 2013, Jorge Mario Bergoglio fue elegido como Sucesor de Pedro, el primer Latinoamericano y primer Papa jesuita y el primero con el nombre de Francisco.<\/p>\n<p>Un Papado marcado por la misericordia Que promueve una Iglesia &#8220;en salida&#8221;, con &#8221; las puertas abiertas&#8221;, un &#8220;hospital de campa\u00f1a&#8221; que no teme la &#8220;revoluci\u00f3n de la ternura&#8221; ni &#8220;el milagro de la gentileza&#8221;.<\/p>\n<p>Estos ocho a\u00f1os de Pontificado se han caracterizado por iniciativas y reformas para implicar a todos los cristianos en un nuevo impulso misionero con el objetivo de llevar el amor de Jes\u00fas a toda la humanidad.<\/p>\n<p>Dios nos ha regalado un Papa con gran humildad, con opci\u00f3n preferencial por los pobres, que ha buscado una Iglesia pobre y para los pobres.<\/p>\n<p>Durante su pontificando nos ha regalado las enc\u00edclicas:<\/p>\n<p>* Lumen fidei, sobre la fe (29 de junio de 2013).<\/p>\n<p>* Laudato si&#8217;, sobre el cuidado de la casa com\u00fan (24 de mayo de 2015).<\/p>\n<p>* Hermanos todos, sobre la fraternidad y la amistad social (3 de octubre de 2020).<\/p>\n<p>Las Exhortaciones apost\u00f3licas:<\/p>\n<p>1. Evangelii Gaudium, sobre el anuncio del Evangelio en el mundo actual (24 de noviembre de 2013).<\/p>\n<p>2. Amoris laetitia, sobre el amor en la familia (19 de marzo de 2016).<\/p>\n<p>3. Gaudete et exsultate, sobre la llamada a la santidad en el mundo contempor\u00e1neo (19 de marzo de 2018).<\/p>\n<p>4. Christus vivit (25 de marzo de 2019).<\/p>\n<p>5. Querida Amazon\u00eda (2 de febrero de 2020).<\/p>\n<p>\u00a1GRACIAS PAPA FRANCISCO!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Juan Pablo V\u00e1zquez Rodr\u00edguez Monterrey, N.L. (www.pastoralsiglo21.org).- 13 de marzo del 2021 El 13 de marzo de 2013, Jorge Mario Bergoglio fue elegido como Sucesor<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":10,"featured_media":14050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,14,6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/14049"}],"collection":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/comments?post=14049"}],"version-history":[{"count":1,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/14049\/revisions"}],"predecessor-version":[{"id":14051,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/posts\/14049\/revisions\/14051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media\/14050"}],"wp:attachment":[{"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/media?parent=14049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/categories?post=14049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arquidiocesismty.org\/arquimty\/wp-json\/wp\/v2\/tags?post=14049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}